{"id":5234,"date":"2017-12-13T17:17:59","date_gmt":"2017-12-13T10:17:59","guid":{"rendered":"https:\/\/www.suzukimotosales.co.th\/news\/%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94%e0%b8%95%e0%b8%b1%e0%b8%a7%e0%b8%ad%e0%b8%a2%e0%b9%88%e0%b8%b2%e0%b8%87%e0%b9%80%e0%b8%9b%e0%b9%87%e0%b8%99%e0%b8%97%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%b2"},"modified":"2018-03-12T19:31:20","modified_gmt":"2018-03-12T12:31:20","slug":"%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94%e0%b8%95%e0%b8%b1%e0%b8%a7%e0%b8%ad%e0%b8%a2%e0%b9%88%e0%b8%b2%e0%b8%87%e0%b9%80%e0%b8%9b%e0%b9%87%e0%b8%99%e0%b8%97%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3","status":"publish","type":"suzuki_news","link":"https:\/\/www.suzukimotosales.co.th\/en\/news\/5234\/","title":{"rendered":"\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23 \u0e01\u0e31\u0e1a SUZUKI NEW MODEL 2017"},"content":{"rendered":"<p>\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e46\u0e17\u0e48\u0e32\u0e19\u0e43\u0e14\u0e2a\u0e19\u0e43\u0e08\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e1a\u0e01\u0e31\u0e1a\u0e15\u0e31\u0e27\u0e08\u0e23\u0e34\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e08\u0e23\u0e34\u0e07\u0e02\u0e2d\u0e07\u0e40\u0e08\u0e49\u0e32 GSX-R1000R, GSX-R1000, V-Strom650XT, V-Strom650 , GSX-R150 \u0e41\u0e25\u0e30 \u0e41\u0e25\u0e30\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e0b\u0e39\u0e0b\u0e39\u0e01\u0e34\u0e23\u0e38\u0e48\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e2d\u0e35\u0e01\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e42\u0e1b\u0e23\u0e42\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e2a\u0e38\u0e14\u0e46 \u0e44\u0e14\u0e49\u0e43\u0e19\u0e07\u0e32\u0e19 Motor Show 2017 \u0e13 \u0e2d\u0e34\u0e21\u0e41\u0e1e\u0e04 \u0e2d\u0e32\u0e23\u0e35\u0e19\u0e48\u0e32 \u0e40\u0e21\u0e37\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e18\u0e32\u0e19\u0e35 ,\u0e0a\u0e32\u0e40\u0e25\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c 1 \u0e2e\u0e2d\u0e25\u0e25\u0e4c 1 \u0e1a\u0e39\u0e18 M5 \u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 29 &#8211; 9 \u0e40\u0e21\u0e29\u0e32\u0e22\u0e19 \u0e19\u0e35\u0e49\u0e04\u0e48\u0e30<br \/>\n*\u0e41\u0e16\u0e21\u0e1a\u0e39\u0e18\u0e40\u0e23\u0e32\u0e22\u0e31\u0e07\u0e21\u0e35\u0e41\u0e27\u0e48\u0e19 VR \u0e43\u0e2b\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e46\u0e44\u0e14\u0e49\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e16\u0e36\u0e07\u0e1f\u0e34\u0e27\u0e23\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e23\u0e16\u0e23\u0e38\u0e48\u0e19 GSX-R1000 \u0e41\u0e1a\u0e1a\u0e40\u0e2a\u0e21\u0e37\u0e2d\u0e19\u0e27\u0e48\u0e32\u0e01\u0e33\u0e25\u0e31\u0e07\u0e02\u0e31\u0e1a\u0e2d\u0e22\u0e39\u0e48\u0e08\u0e23\u0e34\u0e07 !!!<\/p>\n<p>\u0e41\u0e25\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e14\u0e39\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48 https:\/\/www.facebook.com\/SuzukiSociety\/<\/p>\n<p>\u0e07\u0e32\u0e19\u0e19\u0e35\u0e49\u0e41\u0e1f\u0e19\u0e0b\u0e39\u0e0b\u0e39\u0e01\u0e34\u0e15\u0e31\u0e27\u0e08\u0e23\u0e34\u0e07\u0e2b\u0e49\u0e32\u0e21\u0e1e\u0e25\u0e32\u0e14\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19&#8230;.\u0e41\u0e25\u0e49\u0e27\u0e1e\u0e1a\u0e01\u0e31\u0e19\u0e19\u0e30\u0e04\u0e30<br \/>\n&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<br \/>\n\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e2a\u0e2d\u0e1a\u0e16\u0e32\u0e21\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48 Suzuki Call Center 02-533-1170<br \/>\n\u0e43\u0e19\u0e40\u0e27\u0e25\u0e32\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e27\u0e31\u0e19\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c &#8211; \u0e28\u0e38\u0e01\u0e23\u0e4c \u0e40\u0e27\u0e25\u0e32 8.00-17.00 \u0e19.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e46\u0e17\u0e48\u0e32\u0e19\u0e43\u0e14\u0e2a\u0e19\u0e43\u0e08\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e1a\u0e01\u0e31\u0e1a\u0e15\u0e31\u0e27\u0e08\u0e23\u0e34\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e08\u0e23\u0e34\u0e07\u0e02\u0e2d\u0e07\u0e40\u0e08\u0e49\u0e32 GSX-R1000R, GSX-R1000, V-Strom650XT, V-Strom650 , GSX-R150 <\/p>\n","protected":false},"featured_media":1796,"template":"","format":"standard","_links":{"self":[{"href":"https:\/\/www.suzukimotosales.co.th\/en\/wp-json\/wp\/v2\/suzuki_news\/5234"}],"collection":[{"href":"https:\/\/www.suzukimotosales.co.th\/en\/wp-json\/wp\/v2\/suzuki_news"}],"about":[{"href":"https:\/\/www.suzukimotosales.co.th\/en\/wp-json\/wp\/v2\/types\/suzuki_news"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suzukimotosales.co.th\/en\/wp-json\/wp\/v2\/media\/1796"}],"wp:attachment":[{"href":"https:\/\/www.suzukimotosales.co.th\/en\/wp-json\/wp\/v2\/media?parent=5234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}